{"id":3975,"date":"2025-03-24T17:17:17","date_gmt":"2025-03-24T14:17:17","guid":{"rendered":"https:\/\/serenityresort.ro\/?page_id=3975"},"modified":"2025-03-27T11:12:41","modified_gmt":"2025-03-27T08:12:41","slug":"easter-in-bloom","status":"publish","type":"page","link":"https:\/\/serenityresort.ro\/en\/easter-in-bloom\/","title":{"rendered":"Easter In Bloom"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div data-bg-media-opacity=\"1\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1698748890343 vc-row-ff4be8b007a05e8040fbfedcddbe6d98-17841176371788329474 vc_column-gap-5 vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t\t<!-- START Easter In Bloom REVOLUTION SLIDER 6.6.15 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_13_1_wrapper\" data-source=\"gallery\" style=\"visibility:hidden;background:rgba(2,2,2,0.5);padding:0;background-image:url(https:\/\/serenityresort.ro\/wp-content\/uploads\/revslider\/home_1_slider\/black.png);background-repeat:no-repeat;background-size:cover;background-position:center center;\">\n\t\t\t\t<rs-module id=\"rev_slider_13_1\" style=\"\" data-version=\"6.6.15\">\n\t\t\t\t\t<rs-slides style=\"overflow: hidden; position: absolute;\">\n\t\t\t\t\t\t<rs-slide style=\"position: absolute;\" data-key=\"rs-40\" data-title=\"Slide1\" data-in=\"o:0;\" data-out=\"a:false;\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"\/\/serenityresort.ro\/wp-content\/plugins\/httpvelikorodnovcomwordpresssample-datapluginusanrevslider\/public\/assets\/assets\/dummy.png\" alt=\"\" title=\"header2\" width=\"2560\" height=\"1440\" class=\"rev-slidebg tp-rs-img rs-lazyload\" data-lazyload=\"\/\/serenityresort.ro\/wp-content\/uploads\/header2-scaled.jpg\" data-parallax=\"off\" data-no-retina>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-13-slide-40-layer-0\" \n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:-3px,-3px,-3px,0;yo:779px,779px,779px,260px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,20,7;l:0,0,0,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:179px,179px,179px,172px;h:40px,40px,40px,38px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;background-color:#89a074;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-13-slide-40-layer-1\" \n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;yo:786px,786px,786px,269px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,20,17;l:25,25,25,22;a:center;\"\n\t\t\t\t\t\t\t\tdata-actions='o:click;a:scrollbelow;offset:6000px;sp:1000ms;e:power1.inOut;'\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"x:0,0,0,0px;y:0,0,0,0px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;font-family:'Open Sans';\"\n\t\t\t\t\t\t\t>Rezerv\u0103-\u021bi locul \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-13-slide-40-layer-5\" \n\t\t\t\t\t\t\t\tdata-type=\"image\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"x:c;xo:0,0,0,-4px;y:m;yo:-176px,-176px,-176px,-241px;\"\n\t\t\t\t\t\t\t\tdata-text=\"w:normal;s:20,20,20,7;l:0,0,0,9;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:486px,486px,486px,300px;h:263px,263px,263px,191px;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;st:w;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;\"\n\t\t\t\t\t\t\t><img decoding=\"async\" src=\"\/\/serenityresort.ro\/wp-content\/plugins\/httpvelikorodnovcomwordpresssample-datapluginusanrevslider\/public\/assets\/assets\/dummy.png\" alt=\"\" class=\"tp-rs-img rs-lazyload\" width=\"590\" height=\"319\" data-lazyload=\"\/\/serenityresort.ro\/wp-content\/uploads\/titlu.png\" data-no-retina> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-static-layers><!--\n\t\t\t\t\t--><\/rs-static-layers>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script>\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_13_1',rl:[1240,1240,1240,480],el:[868,868,868,720],gw:[1240,1240,1240,480],gh:[868,868,868,720],type:'standard',justify:'',layout:'fullscreen',offsetContainer:'#milenia-header:not(.milenia-header--transparent-single)',offset:'',mh:\"0\"});if (window.RS_MODULES!==undefined && window.RS_MODULES.modules!==undefined && window.RS_MODULES.modules[\"revslider131\"]!==undefined) {window.RS_MODULES.modules[\"revslider131\"].once = false;window.revapi13 = undefined;if (window.RS_MODULES.checkMinimal!==undefined) window.RS_MODULES.checkMinimal()}\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n<\/div><\/div><\/div><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742810077758 vc-row-9d9ab4969e7574d566c11aef49355847-17841176371850520715 vc_row-has-fill\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742823022851 vc-row-63caae003e91ade09837755b6a485c61-17841176372115779743 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><!--================ Section Heading ================-->\n<script>\n    (function($){\n        'use strict';\n\n        if(!$) return;\n\n        $(function(){\n            if(window.appear) {\n                appear({\n                    elements: function(){\n                        return document.querySelectorAll('#vc-milenia-section-heading-618649bffbde8d48937dd1ce396f5606-17841176371221468050');\n                    },\n                    appear: function(element) {\n                        var $el = $(element);\n                        $el.addClass('milenia-visible').addClass($el.data('animation'));\n                    },\n                    reappear: false,\n                    bounds: -200\n                });\n            }\n        });\n    })(window.jQuery);\n<\/script>\n<div id=\"vc-milenia-section-heading-618649bffbde8d48937dd1ce396f5606-17841176371221468050\" class=\"milenia-section-heading text-center vc_custom_1742814178847 milenia-visible\" data-animation=\"none\">\n    \n    <h2 class=\"milenia-section-title milenia-font--like-body\" style=\"color: #ffffff;font-size: 96px;line-height: 80px;margin-bottom: 37px;text-transform: none;font-style: italic;font-weight: 400;\">19-22 APRILIE 2025<\/h2>\n\n    \n<\/div>\n<!--================ End of Section Heading ================-->\n<div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><!--================ Section Heading ================-->\n<script>\n    (function($){\n        'use strict';\n\n        if(!$) return;\n\n        $(function(){\n            if(window.appear) {\n                appear({\n                    elements: function(){\n                        return document.querySelectorAll('#vc-milenia-section-heading-48d09f0789ea3b6c23915003fded3121-1784117637603763688');\n                    },\n                    appear: function(element) {\n                        var $el = $(element);\n                        $el.addClass('milenia-visible').addClass($el.data('animation'));\n                    },\n                    reappear: false,\n                    bounds: -200\n                });\n            }\n        });\n    })(window.jQuery);\n<\/script>\n<div id=\"vc-milenia-section-heading-48d09f0789ea3b6c23915003fded3121-1784117637603763688\" class=\"milenia-section-heading text-center  milenia-visible\" data-animation=\"none\">\n    \n    <h2 class=\"milenia-section-title milenia-font--like-body\" style=\"color: #ffffff;font-size: 32px;line-height: 40px;margin-bottom: 0px;text-transform: none;font-style: normal;font-weight: 400;\">Tradi\u021bie, relaxare \u0219i bucurie \u2013 te invit\u0103m s\u0103 tr\u0103ie\u0219ti magia s\u0103rb\u0103torilor pascale \u00eentr-un loc unic, ideal pentru momente autentice cu cei dragi.<\/h2>\n\n    \n<\/div>\n<!--================ End of Section Heading ================-->\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div>\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_slideInDown slideInDown  sageata\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/serenityresort.ro\/en\/easter-in-bloom\/\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250214_SERENITY_WEB-08-300x300.png\" class=\"vc_single_image-img attachment-medium\" alt=\"\" title=\"250214_SERENITY_WEB-08\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250214_SERENITY_WEB-08-300x300.png 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250214_SERENITY_WEB-08-150x150.png 150w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250214_SERENITY_WEB-08-12x12.png 12w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250214_SERENITY_WEB-08.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742814814706 vc-row-93a46f7a5e40e07c6e2c0ad51e3a5738-1784117637987375304 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"1440\" height=\"2560\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"250324_SERENITY_WEB PASTE-03\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-scaled.jpg 1440w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-169x300.jpg 169w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-576x1024.jpg 576w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-768x1365.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-864x1536.jpg 864w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-1152x2048.jpg 1152w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-03-1-7x12.jpg 7w\" sizes=\"auto, (max-width: 1440px) 100vw, 1440px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742814727711 vc-row-103e1686d16c762c0754e7f0469beaf3-17841176371686157214 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  vc_custom_1742816989692\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1284\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"250324_SERENITY_WEB PASTE-02\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-scaled.jpg 2560w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-300x151.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-1024x514.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-768x385.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-1536x771.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-2048x1027.jpg 2048w, https:\/\/serenityresort.ro\/wp-content\/uploads\/250324_SERENITY_WEB-PASTE-02-18x9.jpg 18w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1739529259372 vc-row-a9eadde98053e10a3b24ca0616156ad2-1784117637678838753 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\".vc-row-a9eadde98053e10a3b24ca0616156ad2-1784117637678838753 .vc_parallax-inner, .vc-row-a9eadde98053e10a3b24ca0616156ad2-1784117637678838753 .vc_video-bg { opacity: 1;}.vc-row-a9eadde98053e10a3b24ca0616156ad2-1784117637678838753 { color: #000000;}\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742976362479 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-1-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 1300px;\" data-interval=\"1500\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"true\" data-per-view=\"2\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/1-01-1024x683.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/1-01.jpg\" width=\"1251\" height=\"835\" alt=\"1-01\" title=\"1-01\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/2-2-683x1024.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/2-2-scaled-1300x900.jpg\" width=\"1300\" height=\"900\" alt=\"2\" title=\"2\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/3-01-01-1024x684.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/3-01-01-1300x900.jpg\" width=\"1300\" height=\"900\" alt=\"3-01-01\" title=\"3-01-01\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/4-01-01-1024x683.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/4-01-01.jpg\" width=\"1251\" height=\"835\" alt=\"4-01-01\" title=\"4-01-01\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/5-01-1024x683.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/5-01-1300x900.jpg\" width=\"1300\" height=\"900\" alt=\"5-01\" title=\"5-01\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/5-2-1024x731.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/5-2.jpg\" width=\"1200\" height=\"857\" alt=\"5\" title=\"5\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/6-1-1024x731.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/6-1.jpg\" width=\"1200\" height=\"857\" alt=\"6\" title=\"6\" loading=\"lazy\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><a class=\"\" href=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/7-1024x731.jpg\" data-lightbox=\"lightbox[rel-3975-1366760362]\"><img decoding=\"async\" class=\"\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/7.jpg\" width=\"1200\" height=\"857\" alt=\"7\" title=\"7\" loading=\"lazy\" \/><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742814814706 vc-row-866c8b3b8b7ca91bd1686f3364457bbb-17841176371319689498 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md vc_hidden-sm vc_col-has-fill\"><div class=\"vc_column-inner vc_custom_1742816330728\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"504\" height=\"2560\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Trei zile de rasfat culinar\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-scaled.jpg 504w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-59x300.jpg 59w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-768x3899.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-403x2048.jpg 403w\" sizes=\"auto, (max-width: 504px) 100vw, 504px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742814727711 vc-row-c1029bd16f15c44066c13231cf8d9d84-1784117637949560020 vc_row-has-fill vc_row-o-content-middle vc_row-flex\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  vc_custom_1742822159352\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Trei-zile-de-rasfat-culinar-si-armonie-scaled.jpg\" width=\"1313\" height=\"2560\" alt=\"Trei zile de rasfat culinar si armonie\" title=\"Trei zile de rasfat culinar si armonie\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" class=\"vc_row wpb_row vc_row-fluid vc-row-d239aa4802cb0fc222be60e85e3d24fa-1784117637232557491\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-lg vc_hidden-md\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  vc_custom_1742823850072\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2546\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"tarife mobile\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-scaled.jpg 2560w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-300x298.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-1024x1019.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-150x150.jpg 150w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-768x764.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-1536x1528.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-2048x2037.jpg 2048w, https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-mobile-12x12.jpg 12w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742826794160 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-2-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"9000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/vila-standard\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1024x683.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1536x1024.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742826799221 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-3-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"9000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/vila-superioara\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"Vila_v-superioara\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1279\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard.jpg\" class=\"attachment-full\" alt=\"\" title=\"v-standard\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1024x682.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1536x1023.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742826803694 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-4-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"9000\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"1\" data-hide-on-end=\"false\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/apartament\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"Vila_apartament\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart.jpg\" class=\"attachment-full\" alt=\"\" title=\"v-apart\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1024x683.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1536x1024.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-bg-media-opacity=\"1\" class=\"vc_row wpb_row vc_row-fluid vc-row-03c3b405f87906b30795fcff07625406-17841176371765372718\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12 vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  vc_custom_1742822326110\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/tarife-1-scaled-1920x831.jpg\" width=\"1920\" height=\"831\" alt=\"tarife\" title=\"tarife\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742823890876 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-5-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"2\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/vila-standard\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1024x683.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1536x1024.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-standard-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742822530246 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-6-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"2\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/vila-superioara\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"Vila_v-superioara\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_v-superioara-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1279\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard.jpg\" class=\"attachment-full\" alt=\"\" title=\"v-standard\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1024x682.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1536x1023.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-standard-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpb_images_carousel wpb_content_element vc_clearfix vc_custom_1742823895917 galerie-8martie\"><div class=\"wpb_wrapper\"><div id=\"vc_images-carousel-7-1784117637\" data-ride=\"vc_carousel\" data-wrap=\"true\" style=\"width: 100%;\" data-interval=\"0\" data-auto-height=\"yes\" data-mode=\"horizontal\" data-partial=\"false\" data-per-view=\"2\" data-hide-on-end=\"true\" class=\"vc_slide vc_images_carousel\"><div class=\"vc_carousel-inner\"><div class=\"vc_carousel-slideline\"><div class=\"vc_carousel-slideline-inner\"><div class=\"vc_item\"><div class=\"vc_inner\"><a href=\"https:\/\/serenityresort.ro\/en\/accommodation\/apartament\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart.jpg\" class=\"attachment-full\" alt=\"\" title=\"v-apart\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart.jpg 1920w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-300x200.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1024x683.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-768x512.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1536x1024.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-18x12.jpg 18w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-1350x900.jpg 1350w, https:\/\/serenityresort.ro\/wp-content\/uploads\/v-apart-660x440.jpg 660w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><\/div><\/div><div class=\"vc_item\"><div class=\"vc_inner\"><img loading=\"lazy\" decoding=\"async\" width=\"2001\" height=\"1339\" src=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1.jpg\" class=\"attachment-full\" alt=\"\" title=\"Vila_apartament\" srcset=\"https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1.jpg 2001w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-300x201.jpg 300w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-1024x685.jpg 1024w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-768x514.jpg 768w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-1536x1028.jpg 1536w, https:\/\/serenityresort.ro\/wp-content\/uploads\/Vila_apartament-1-18x12.jpg 18w\" sizes=\"auto, (max-width: 2001px) 100vw, 2001px\" \/><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742822713793 vc-row-8aed5291f580de54cf1b2cacfb90353d-17841176372069254362 vc_row-has-fill\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><!--================ Section Heading ================-->\n<script>\n    (function($){\n        'use strict';\n\n        if(!$) return;\n\n        $(function(){\n            if(window.appear) {\n                appear({\n                    elements: function(){\n                        return document.querySelectorAll('#vc-milenia-section-heading-8aa1c8165d4997e2a7ab5c91e64ce58e-1784117637124685800');\n                    },\n                    appear: function(element) {\n                        var $el = $(element);\n                        $el.addClass('milenia-visible').addClass($el.data('animation'));\n                    },\n                    reappear: false,\n                    bounds: -200\n                });\n            }\n        });\n    })(window.jQuery);\n<\/script>\n<div id=\"vc-milenia-section-heading-8aa1c8165d4997e2a7ab5c91e64ce58e-1784117637124685800\" class=\"milenia-section-heading text-center vc_custom_1742822695967 milenia-visible\" data-animation=\"none\">\n    \n    <h2 class=\"milenia-section-title milenia-font--like-body\" style=\"color: #6c6c6c;font-size: 62px;line-height: 58px;margin-bottom: 37px;text-transform: none;font-style: italic;font-weight: 400;\">Rezerv\u0103-\u021bi locul<\/h2>\n\n    \n<\/div>\n<!--================ End of Section Heading ================-->\n<div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_10 vc_sep_pos_align_center vc_separator_no_text\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span style=\"border-color:#6c6c6c;\" class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span style=\"border-color:#6c6c6c;\" class=\"vc_sep_line\"><\/span><\/span>\n<\/div><!--================ Section Heading ================-->\n<script>\n    (function($){\n        'use strict';\n\n        if(!$) return;\n\n        $(function(){\n            if(window.appear) {\n                appear({\n                    elements: function(){\n                        return document.querySelectorAll('#vc-milenia-section-heading-4be135607c22b78037fe908b363fa87b-1784117637353212361');\n                    },\n                    appear: function(element) {\n                        var $el = $(element);\n                        $el.addClass('milenia-visible').addClass($el.data('animation'));\n                    },\n                    reappear: false,\n                    bounds: -200\n                });\n            }\n        });\n    })(window.jQuery);\n<\/script>\n<div id=\"vc-milenia-section-heading-4be135607c22b78037fe908b363fa87b-1784117637353212361\" class=\"milenia-section-heading text-center vc_custom_1739783461126 milenia-visible\" data-animation=\"none\">\n    \n    <h2 class=\"milenia-section-title milenia-font--first-accented\" style=\"color: #6c6c6c;font-size: 22px;line-height: 40px;margin-bottom: 37px;text-transform: none;font-style: normal;font-weight: 400;\">V\u0103 rug\u0103m s\u0103 completa\u021bi formularul de mai jos.<\/h2>\n\n    \n<\/div>\n<!--================ End of Section Heading ================-->\n<!--================ Section Heading ================-->\n<script>\n    (function($){\n        'use strict';\n\n        if(!$) return;\n\n        $(function(){\n            if(window.appear) {\n                appear({\n                    elements: function(){\n                        return document.querySelectorAll('#vc-milenia-section-heading-095b0ba44e363477dc02fdbf0d30ddb5-17841176372119673251');\n                    },\n                    appear: function(element) {\n                        var $el = $(element);\n                        $el.addClass('milenia-visible').addClass($el.data('animation'));\n                    },\n                    reappear: false,\n                    bounds: -200\n                });\n            }\n        });\n    })(window.jQuery);\n<\/script>\n<div id=\"vc-milenia-section-heading-095b0ba44e363477dc02fdbf0d30ddb5-17841176372119673251\" class=\"milenia-section-heading text-center vc_custom_1739783498184 milenia-visible\" data-animation=\"none\">\n    \n    <h2 class=\"milenia-section-title milenia-font--first-accented\" style=\"color: #6c6c6c;font-size: 22px;line-height: 40px;text-transform: none;font-style: normal;font-weight: 400;\">V\u0103 mul\u021bumim \u0219i v\u0103 a\u0219teptam.<\/h2>\n\n    \n<\/div>\n<!--================ End of Section Heading ================-->\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><div data-bg-media-opacity=\"1\" data-vc-full-width=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1742822610745 vc-row-06650c0e33bc6911de438481cdb694da-1784117637899729914 vc_row-has-fill\" data-css-row=\"\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div id=\"8martie\" class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1739538429901 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3976-o1\" lang=\"ro-RO\" dir=\"ltr\" data-wpcf7-id=\"3976\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/3975#wpcf7-f3976-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formular de contact\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/en\/wp-json\/wp\/v2\/pages\/3975#wpcf7-f3976-o1\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3976\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.0.4\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"ro_RO\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3976-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/div>\n<div class=\"c-grid\">\n\t<p><label> NUME \u0218I PRENUME *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"name\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> NUM\u0102R DE PERSOANE *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"numar-persoane\"><input class=\"wpcf7-form-control wpcf7-number wpcf7-validates-as-required wpcf7-validates-as-number\" min=\"1\" max=\"999\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"number\" name=\"numar-persoane\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> TELEFON *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tel-207\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-207\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> OFERT\u0102 DORIT\u0102<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"event\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"Easter In Bloom\" type=\"text\" name=\"event\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> ADRES\u0102 DE MAIL *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\n\t<\/p>\n\t<p><label> MESAJ<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\">Men\u021bioneaz\u0103 tipul de cazare dorit (Vil\u0103 Standard \/ Vil\u0103 Superioar\u0103 \/ Apartament)<\/textarea><\/span> <\/label>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"REZERV\u0102\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"en\"\/><\/form>\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Rezerv\u0103-\u021bi locul 19-22 APRILIE 2025 Tradi\u021bie, relaxare \u0219i bucurie \u2013 te invit\u0103m s\u0103 tr\u0103ie\u0219ti magia s\u0103rb\u0103torilor pascale \u00eentr-un...","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3975","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/pages\/3975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/comments?post=3975"}],"version-history":[{"count":60,"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/pages\/3975\/revisions"}],"predecessor-version":[{"id":4079,"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/pages\/3975\/revisions\/4079"}],"wp:attachment":[{"href":"https:\/\/serenityresort.ro\/en\/wp-json\/wp\/v2\/media?parent=3975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}